{"id":398,"date":"2007-12-11T23:00:05","date_gmt":"2007-12-11T21:00:05","guid":{"rendered":"http:\/\/www.mitternachtshacking.de\/blog\/398-herstellerzertifizierungskrampf-und-lustige-kurzel"},"modified":"2012-06-07T09:55:07","modified_gmt":"2012-06-07T08:55:07","slug":"herstellerzertifizierungskrampf-und-lustige-kurzel","status":"publish","type":"post","link":"https:\/\/www.mitternachtshacking.de\/blog\/398-herstellerzertifizierungskrampf-und-lustige-kurzel","title":{"rendered":"Herstellerzertifizierungskrampf und lustige K\u00fcrzel"},"content":{"rendered":"<p>Die Check Point Zertifizierungen gehen mir langsam auf die Nerven &#8230; alle paar Jahre wieder den ganzen Krampf.\u00c2\u00a0 Hab deshalb heute noch schnell zum Jahresende was gemacht. Was bin ich jetzt alles:<\/p>\n<ul>\n<li>CCSA NGX<\/li>\n<li>CCSE NGX<\/li>\n<li>CCSE PLUS NGX<\/li>\n<li>CCMSE NGX<\/li>\n<\/ul>\n<p>und was fehlt mir noch alles:<\/p>\n<ul>\n<li>CCMSE NGX PLUS VSX<\/li>\n<li>CPCS Connectra<\/li>\n<li>CPCS Integrity<\/li>\n<li>CPCS IPS-1<\/li>\n<\/ul>\n<p>Den VSX mach ich zum Jahresende noch schnell aber der Rest hat Zeit bis n\u00e4chstes Jahr.<\/p>\n<p>Ich stell mir grad vor, die das auf einer Visitenkarte aussehen w\u00fcrde. Die Amis drucken da doch jeden Bl\u00f6dsinn drauf. Ich schreibe dagegen bei mir weder Dipl.-Inf. noch CISSP drauf, das ist mir echt zu doof \ud83d\ude42<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Check Point Zertifizierungen gehen mir langsam auf die Nerven &#8230; alle paar Jahre wieder den ganzen Krampf.\u00c2\u00a0 Hab deshalb heute noch schnell zum Jahresende was gemacht. Was bin ich jetzt alles: CCSA NGX CCSE NGX CCSE PLUS NGX CCMSE NGX und was fehlt mir noch alles: CCMSE NGX PLUS VSX CPCS Connectra CPCS Integrity [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mitternachtshacking.de\/blog\/wp-json\/wp\/v2\/posts\/398"}],"collection":[{"href":"https:\/\/www.mitternachtshacking.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mitternachtshacking.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mitternachtshacking.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mitternachtshacking.de\/blog\/wp-json\/wp\/v2\/comments?post=398"}],"version-history":[{"count":0,"href":"https:\/\/www.mitternachtshacking.de\/blog\/wp-json\/wp\/v2\/posts\/398\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mitternachtshacking.de\/blog\/wp-json\/wp\/v2\/media?parent=398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mitternachtshacking.de\/blog\/wp-json\/wp\/v2\/categories?post=398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mitternachtshacking.de\/blog\/wp-json\/wp\/v2\/tags?post=398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}